{"id":1627,"date":"2017-02-08T10:21:06","date_gmt":"2017-02-08T10:21:06","guid":{"rendered":"https:\/\/www.vets-now.com\/professionals\/?page_id=1627"},"modified":"2026-02-23T08:40:52","modified_gmt":"2026-02-23T08:40:52","slug":"vets-now-bank-holiday-planner","status":"publish","type":"page","link":"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/","title":{"rendered":"Vets Now Bank Holiday Planner"},"content":{"rendered":"<h2>Bank holidays 2026<\/h2>\n<p>See the upcoming bank holiday cover for your local Vets Now clinic below.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bank holidays 2026 See the upcoming bank holiday cover for your local Vets Now clinic below.<\/p>\n","protected":false},"author":15,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v20.3 (Yoast SEO v22.3) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vets Now Bank Holiday Planner 2026<\/title>\n<meta name=\"description\" content=\"Bank holiday planner - where we cover a holiday, we will open at our usual time on the night\/day prior and will close at the regular time the next day.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vets Now Bank Holiday Planner\" \/>\n<meta property=\"og:description\" content=\"Bank holiday planner - where we cover a holiday, we will open at our usual time on the night\/day prior and will close at the regular time the next day.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/\" \/>\n<meta property=\"og:site_name\" content=\"Vets Now Professionals\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T08:40:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/\",\"url\":\"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/\",\"name\":\"Vets Now Bank Holiday Planner 2026\",\"isPartOf\":{\"@id\":\"https:\/\/www.vets-now.com\/professionals\/#website\"},\"datePublished\":\"2017-02-08T10:21:06+00:00\",\"dateModified\":\"2026-02-23T08:40:52+00:00\",\"description\":\"Bank holiday planner - where we cover a holiday, we will open at our usual time on the night\/day prior and will close at the regular time the next day.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vets-now.com\/professionals\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vets Now Bank Holiday Planner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vets-now.com\/professionals\/#website\",\"url\":\"https:\/\/www.vets-now.com\/professionals\/\",\"name\":\"Vets Now Professionals\",\"description\":\"A dedicate site for Vets Now Professional services\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vets-now.com\/professionals\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vets Now Bank Holiday Planner 2026","description":"Bank holiday planner - where we cover a holiday, we will open at our usual time on the night\/day prior and will close at the regular time the next day.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/","og_locale":"en_GB","og_type":"article","og_title":"Vets Now Bank Holiday Planner","og_description":"Bank holiday planner - where we cover a holiday, we will open at our usual time on the night\/day prior and will close at the regular time the next day.","og_url":"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/","og_site_name":"Vets Now Professionals","article_modified_time":"2026-02-23T08:40:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/","url":"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/","name":"Vets Now Bank Holiday Planner 2026","isPartOf":{"@id":"https:\/\/www.vets-now.com\/professionals\/#website"},"datePublished":"2017-02-08T10:21:06+00:00","dateModified":"2026-02-23T08:40:52+00:00","description":"Bank holiday planner - where we cover a holiday, we will open at our usual time on the night\/day prior and will close at the regular time the next day.","breadcrumb":{"@id":"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vets-now.com\/professionals\/vets-now-bank-holiday-planner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vets-now.com\/professionals\/"},{"@type":"ListItem","position":2,"name":"Vets Now Bank Holiday Planner"}]},{"@type":"WebSite","@id":"https:\/\/www.vets-now.com\/professionals\/#website","url":"https:\/\/www.vets-now.com\/professionals\/","name":"Vets Now Professionals","description":"A dedicate site for Vets Now Professional services","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vets-now.com\/professionals\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/pages\/1627"}],"collection":[{"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/comments?post=1627"}],"version-history":[{"count":338,"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/pages\/1627\/revisions"}],"predecessor-version":[{"id":19102,"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/pages\/1627\/revisions\/19102"}],"wp:attachment":[{"href":"https:\/\/www.vets-now.com\/professionals\/wp-json\/wp\/v2\/media?parent=1627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}